{"id":3029,"date":"2024-03-19T14:18:26","date_gmt":"2024-03-19T19:18:26","guid":{"rendered":"https:\/\/nayandtheplanet.com\/?p=3029"},"modified":"2025-03-18T18:03:33","modified_gmt":"2025-03-18T23:03:33","slug":"imigrar-para-o-canada","status":"publish","type":"post","link":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/","title":{"rendered":"Como imigrar para o Canad\u00e1"},"content":{"rendered":"\n<p>Neste post, eu vou te contar como imigrar para o Canad\u00e1 e se tornar um residente permanente neste pa\u00eds multicultural que oferece alta qualidade de vida para sua popula\u00e7\u00e3o e muitas oportunidades para imigrantes.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"Como imigrar pro Canad\u00e1 (2025)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/o7p84QicTA4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Mas por que o Canad\u00e1 precisa de imigrantes?<\/strong><\/p>\n\n\n\n<p>Apesar de ser o segundo maior do mundo, apenas 0.5% da popula\u00e7\u00e3o mundial vive no pa\u00eds. Por esses e outros motivos, <strong>o Canad\u00e1 vem enfrentando desafios demogr\u00e1ficos por ter uma popula\u00e7\u00e3o mais envelhecida e baixas taxas de natalidade<\/strong>.<\/p>\n\n\n\n<p>A solu\u00e7\u00e3o que o governo encontrou para solucionar esse problema foi exatamente <strong>recepcionar imigrantes de todos os continentes<\/strong> para garantir que a economia continue a crescer.<\/p>\n\n\n\n<p>Em 2021, o Canad\u00e1 bateu um recorde de imigra\u00e7\u00e3o, ap\u00f3s mais de 100 anos, ao receber aproximadamente <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/news\/2021\/12\/canada-welcomes-the-most-immigrants-in-a-single-year-in-its-history.html\" target=\"_blank\" rel=\"noreferrer noopener\">405,000 novos residentes permanentes<\/a>, os <em>permanent residents<\/em> (PR). O governo canadense prev\u00ea ainda que at\u00e9 2036, os imigrantes poder\u00e3o representar at\u00e9 30% da popula\u00e7\u00e3o do Canad\u00e1, em compara\u00e7\u00e3o com 20,7% em 2011.<\/p>\n\n\n\n<p>Estou passando pelo processo de imigra\u00e7\u00e3o no Canad\u00e1 em 2024 e fiz uma extensa pesquisa para resumir <strong>tudo que voc\u00ea precisa saber sobre como imigrar para o Canad\u00e1<\/strong>.<\/p>\n\n\n\n<p><strong>Uma das maneiras mais efetivas \u00e9 <\/strong><a href=\"https:\/\/nayandtheplanet.com\/pt-br\/faculdade-no-canada\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>atrav\u00e9s dos estudos<\/strong><\/a>. Eles valorizam muito a forma\u00e7\u00e3o intelectual e oferecem ensino de qualidade para cidad\u00e3os e imigrantes, o que tamb\u00e9m facilita com que esses estudantes consigam um emprego no Canad\u00e1.<\/p>\n\n\n\n<p>Al\u00e9m disso, algumas <a href=\"https:\/\/br.indeed.com\/conselho-de-carreira\/encontrando-emprego\/profissoes-demanda-canada\" target=\"_blank\" rel=\"noreferrer noopener\">profiss\u00f5es em demanda no Canad\u00e1<\/a> fazem com que profissionais dessas determinadas \u00e1reas consigam imigrar mais facilmente. No entanto, independente da sua \u00e1rea de atua\u00e7\u00e3o, existem v\u00e1rios programas de imigra\u00e7\u00e3o do pa\u00eds que oferecem oportunidades para pessoas do mundo todo.Confira quais s\u00e3o os <strong>programas de imigra\u00e7\u00e3o do Canad\u00e1<\/strong> e quais os requisitos para imigrar por meio de cada um deles!<\/p>\n\n\n\t\t\t\t<div class=\"wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-1  uagb-block-6f17d961 wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-undefined uagb-block-6f17d961     \"\n\t\t\t\t\tdata-scroll= \"1\"\n\t\t\t\t\tdata-offset= \"30\"\n\t\t\t\t\tstyle=\"\"\n\t\t\t\t>\n\t\t\t\t<div class=\"uagb-toc__wrap\">\n\t\t\t\t\t\t<div class=\"uagb-toc__title\">\n\t\t\t\t\t\t\t\u00cdndice\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uagb-toc__list-wrap \">\n\t\t\t\t\t\t<ol class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#1-express-entry-a-forma-mais-r\u00e1pida-de-imigrar-para-o-canad\u00e1\" class=\"uagb-toc-link__trigger\">1- Express Entry: A forma mais r\u00e1pida de imigrar para o Canad\u00e1<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#canadian-experience-class\" class=\"uagb-toc-link__trigger\">Canadian Experience Class<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#federal-skilled-worker-program\" class=\"uagb-toc-link__trigger\">Federal Skilled Worker Program<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#federal-skilled-trades-program\" class=\"uagb-toc-link__trigger\">Federal Skilled Trades Program<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#como-funciona-o-express-entry-e-como-aplicar\" class=\"uagb-toc-link__trigger\">Como funciona o Express Entry e como aplicar<\/a><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#2-provincial-nominee-programs-pnps-nomia\u00e7\u00f5es-provinciais-para-imigrar-para-o-canad\u00e1\" class=\"uagb-toc-link__trigger\">2- Provincial Nominee Programs (PNPs): Nomia\u00e7\u00f5es Provinciais para imigrar para o Canad\u00e1<\/a><li class=\"uagb-toc__list\"><a href=\"#3-atlantic-immigration-program-imigre-para-as-prov\u00edncias-do-atl\u00e2ntico\" class=\"uagb-toc-link__trigger\">3- Atlantic Immigration Program: Imigre para as prov\u00edncias do atl\u00e2ntico<\/a><li class=\"uagb-toc__list\"><a href=\"#4-quebec-programas-de-imigra\u00e7\u00e3o-espec\u00edficos-da-prov\u00edncia-franc\u00f3fona-do-canad\u00e1\" class=\"uagb-toc-link__trigger\">4- Quebec: Programas de imigra\u00e7\u00e3o espec\u00edficos da prov\u00edncia franc\u00f3fona do Canad\u00e1<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#como-funciona-a-imigra\u00e7\u00e3o-do-quebec-e-como-aplicar\" class=\"uagb-toc-link__trigger\">Como funciona a imigra\u00e7\u00e3o do Quebec e como aplicar<\/a><\/li><\/ul><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#5-programas-de-imigra\u00e7\u00e3o-para-profiss\u00f5es-espec\u00edficas\" class=\"uagb-toc-link__trigger\">5- Programas de imigra\u00e7\u00e3o para profiss\u00f5es espec\u00edficas<\/a><li class=\"uagb-toc__list\"><a href=\"#6-family-sponsorship-com-o-patroc\u00ednio-de-um-residente-permanente-ou-cidad\u00e3o-canadense\" class=\"uagb-toc-link__trigger\">6- Family Sponsorship: Com o patroc\u00ednio de um residente permanente ou cidad\u00e3o canadense<\/a><li class=\"uagb-toc__list\"><a href=\"#n\u00e3o-faltam-oportunidades-para-imigrar-para-o-canad\u00e1\" class=\"uagb-toc-link__trigger\">N\u00e3o faltam oportunidades para imigrar para o Canad\u00e1<\/a><\/ul><\/ul><\/ol>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1- Express Entry: A forma mais r\u00e1pida de imigrar para o Canad\u00e1<\/h2>\n\n\n\n<p>O programa Express Entry (EE) \u00e9 uma programa de imigra\u00e7\u00e3o do Canad\u00e1 que ajuda <strong>trabalhadores qualificados, com experi\u00eancia e dentro das profiss\u00f5es exigidas nos requisitos,<\/strong> a se tornarem residentes permanentes do pa\u00eds em menos de 6 meses.<\/p>\n\n\n\n<p>Ele foi criado pelo governo do Canad\u00e1 em 2015 com o objetivo de facilitar a imigra\u00e7\u00e3o expressa de trabalhadores que t\u00eam maior probabilidade de obter sucesso e impulsionar a economia do pa\u00eds.<\/p>\n\n\n\n<p>Isso inclui residentes tempor\u00e1rios que j\u00e1 est\u00e3o empregados no Canad\u00e1, trabalhadores qualificados de outros pa\u00edses que receberam uma oferta de trabalho e profissionais t\u00e9cnicos, chamados de <em>skilled trades<\/em>.<\/p>\n\n\n\n<p>Sendo assim, <strong>o Express Entry possui 3 <\/strong><strong><em>streams<\/em><\/strong>, ou ramifica\u00e7\u00f5es, com diferentes requisitos cada. Confira a seguir!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Canadian Experience Class<\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/express-entry\/eligibility\/canadian-experience-class.html\" target=\"_blank\" rel=\"noreferrer noopener\">Canadian Experience Class<\/a> \u00e9 o programa do Express Entry feito para imigrantes com <strong>experi\u00eancia de trabalho canadense<\/strong> se tornarem residentes permanentes.<\/p>\n\n\n\n<p>Os dois requisitos m\u00ednimos s\u00e3o:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ao menos 1 ano de experi\u00eancia de trabalho canadense<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Trabalho legal e assalariado, como residente tempor\u00e1rio, no Canad\u00e1;<\/li>\n\n\n\n<li>Trabalhos aut\u00f4nomos e o trabalho enquanto estudante em hor\u00e1rio integral, como o Co-op por exemplo, n\u00e3o contam;<\/li>\n\n\n\n<li>O trabalho precisa estar listado na <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/express-entry\/eligibility\/find-national-occupation-code.html\" target=\"_blank\" rel=\"noreferrer noopener\">Classifica\u00e7\u00e3o Nacional de Ocupa\u00e7\u00f5es (NOC)<\/a> e estar nos n\u00edveis de <em>training, education, experience and responsibilities<\/em> (TEER) 0, 1, 2, 3, sendo 0 o n\u00edvel mais qualificado.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Profici\u00eancia em ingl\u00eas ou franc\u00eas<\/h4>\n\n\n\n<p>Apresentar os resultados dos testes aceitos para comprovar profici\u00eancia em ao menos uma das l\u00ednguas oficiais do Canad\u00e1.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os testes aceitos para comprovar o ingl\u00eas s\u00e3o: CELPIP, <a href=\"https:\/\/nayandtheplanet.com\/pt-br\/como-se-dar-bem-no-ielts-saiba-tudo-sobre-essa-prova-de-proficiencia-em-ingles\/\" target=\"_blank\" rel=\"noreferrer noopener\">IELTS<\/a> e PTE Core;<\/li>\n\n\n\n<li>Os testes aceitos para comprovar o franc\u00eas s\u00e3o: TEF Canada e TCF Canad\u00e1;<\/li>\n\n\n\n<li>N\u00edvel m\u00ednimo: CLB\/NCLC 7 para trabalhos no TEER 0 ou 1 da NOC;<\/li>\n\n\n\n<li>N\u00edvel m\u00ednimo: CLB\/NCLC 5 para trabalhos no TEER 2 e 3 da NOC;<\/li>\n\n\n\n<li>Os testes s\u00e3o aceitos se tiverem sido feitos h\u00e1 menos de 2 anos da aplica\u00e7\u00e3o.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Federal Skilled Worker Program<\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/express-entry\/eligibility\/federal-skilled-workers.html\" target=\"_blank\" rel=\"noreferrer noopener\">Federal Skilled Worker<\/a> \u00e9 o programa do Express Entry feito para <strong>trabalhadores qualificados de outros pa\u00edses<\/strong> que desejam viver permanentemente no Canad\u00e1.<\/p>\n\n\n\n<p>Os requisitos m\u00ednimos para ser eleg\u00edvel neste programa s\u00e3o:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ao menos 1 ano de trabalho qualificado<\/h4>\n\n\n\n<p>Experi\u00eancia de trabalho em profiss\u00f5es TEER 0, 1, 2 e 3 da NOC.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O trabalho precisa ser pago e em tempo integral ou o equivalente em horas para trabalhos de meio-per\u00edodo;<\/li>\n\n\n\n<li>Somente a experi\u00eancia adquirida nos \u00faltimos 10 anos \u00e9 v\u00e1lida.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Profici\u00eancia em ingl\u00eas ou franc\u00eas<\/h4>\n\n\n\n<p>Comprovada com resultado de uma prova oficial e v\u00e1lida at\u00e9 2 anos antes da aplica\u00e7\u00e3o. N\u00edvel m\u00ednimo CLB\/NCLC 7 para trabalhos TEER 0 ou 1 da NOC e CLB\/NCLC 5 para trabalhos TEER 2 e 3 da NOC.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Forma\u00e7\u00e3o na \u00e1rea<\/h4>\n\n\n\n<p>Certificado de conclus\u00e3o dos seus estudos.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Certificado canadense;<\/li>\n\n\n\n<li>Se seu certificado de conclus\u00e3o n\u00e3o for do Canad\u00e1, voc\u00ea tamb\u00e9m precisa obter uma avalia\u00e7\u00e3o de credencial, chamada de <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/express-entry\/documents\/education-assessed.html\" target=\"_blank\" rel=\"noreferrer noopener\">Educational Credential Assessment (ECA)<\/a>.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Job Offer<\/h4>\n\n\n\n<p>Oferta de v\u00e1lida trabalho, pago, em tempo integral, entre o TEER 0 e 3 da NOC, e para ao menos um ano no Canad\u00e1.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A empresa precisa ter uma <a href=\"https:\/\/www.canada.ca\/en\/employment-social-development\/services\/foreign-workers.html\" target=\"_blank\" rel=\"noreferrer noopener\">Avalia\u00e7\u00e3o de Impacto no Mercado de Trabalho (LMIA)<\/a>;<\/li>\n\n\n\n<li>Caso n\u00e3o tenha a <em>job offer<\/em>, seu perfil ainda pode ser considerado, mas voc\u00ea ter\u00e1 que apresentar comprova\u00e7\u00e3o financeira.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Elegibilidade<\/h4>\n\n\n\n<p>Al\u00e9m de ter os requisitos m\u00ednimos, voc\u00ea precisa ser eleg\u00edvel para o Federal Skilled Worker. Eles ir\u00e3o avaliar seu perfil nos seguintes quesitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>N\u00edvel de ingl\u00eas ou\/e franc\u00eas:<\/strong> quanto mais avan\u00e7ado, melhor. Se tiver as duas l\u00ednguas, voc\u00ea recebe mais pontos;<\/li>\n\n\n\n<li><strong>Educa\u00e7\u00e3o:<\/strong> quanto mais alto o n\u00edvel, mais pontos voc\u00ea receber\u00e1. Por exemplo: p\u00f3s-gradua\u00e7\u00e3o &gt; bacharelado &gt; curso t\u00e9cnico;<\/li>\n\n\n\n<li><strong>Experi\u00eancia de trabalho:<\/strong> quanto mais e mais qualificado, melhor. Exemplo: a pontua\u00e7\u00e3o m\u00e1xima \u00e9 para 6+ anos em uma profiss\u00e3o do TEER 0 na NOC;<\/li>\n\n\n\n<li><strong>Idade:<\/strong> somente maiores de 18 anos e a pontua\u00e7\u00e3o m\u00e1xima \u00e9 para 18 a 35 anos. Cada ano a mais, menos 1 ponto;<\/li>\n\n\n\n<li><strong>Job offer:<\/strong> se voc\u00ea tiver uma oferta de trabalho de um empregador canadense;<\/li>\n\n\n\n<li><strong>Adaptabilidade:<\/strong> avalia a adapta\u00e7\u00e3o no Canad\u00e1 (sua e do seu c\u00f4njuge, se tiver) com base no n\u00edvel de profici\u00eancia nas l\u00ednguas oficiais, estudos, trabalho e parentes no pa\u00eds.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Esses 6 fatores ser\u00e3o avaliados quando voc\u00ea criar um perfil no EE e ser\u00e1 atribu\u00edda uma nota entre 0 e 100. Para ser eleg\u00edvel no Federal Skilled Worker Program, voc\u00ea precisa de pelo menos 67 pontos. Mas isso n\u00e3o significa que voc\u00ea pode aplicar.<\/p>\n\n\n\n<p>Vou falar sobre a aplica\u00e7\u00e3o mais a frente. Continue lendo!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Federal Skilled Trades Program<\/h3>\n\n\n\n<p>O Federal Skilled Trades \u00e9 um programa do Express Entry que facilita a imigra\u00e7\u00e3o de <strong>trabalhadores de of\u00edcios qualificados<\/strong>, os <em>skilled trades<\/em>, para o Canad\u00e1.<\/p>\n\n\n\n<p>Os of\u00edcios qualificados ou <em>skilled trades<\/em>, em ingl\u00eas, s\u00e3o ocupa\u00e7\u00f5es que geralmente exigem um aprendizado pr\u00e1tico extenso e, em muitos casos, a conclus\u00e3o de um programa de aprendizagem ou certifica\u00e7\u00e3o para se tornar qualificado. Alguns exemplos de profiss\u00f5es s\u00e3o: carpintaria, encanamento, eletricidade, soldagem e mec\u00e2nica.<\/p>\n\n\n\n<p>Os requisitos m\u00ednimos do Skilled Trades Program s\u00e3o:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ao menos 2 anos de experi\u00eancia na profiss\u00e3o<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Experi\u00eancia em tempo integral em of\u00edcios qualificados dentro de 5 anos antes da aplica\u00e7\u00e3o;<\/li>\n\n\n\n<li>A experi\u00eancia de trabalho precisa estar de acordo com os requisitos de uma das profiss\u00f5es dos seguintes grupos da NOC: 72, 73, 82, 83, 92, 93 (menos a 932), 6320 ou 62200. <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/express-entry\/eligibility\/find-national-occupation-code.html\" target=\"_blank\" rel=\"noreferrer noopener\">Confira as profiss\u00f5es listadas na NOC aqui.<\/a><\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Job offer ou certificado de qualifica\u00e7\u00e3o<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Oferta v\u00e1lida de trabalho em tempo integral para ao menos 1 ano;<\/li>\n\n\n\n<li>Certificado de qualifica\u00e7\u00e3o emitido por uma autoridade canadense;<\/li>\n\n\n\n<li>Caso n\u00e3o tenha uma <em>job offer<\/em> e n\u00e3o tenha uma permiss\u00e3o de trabalho no Canad\u00e1, voc\u00ea tamb\u00e9m precisar\u00e1 de comprova\u00e7\u00e3o financeira.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Profici\u00eancia em ingl\u00eas ou franc\u00eas<\/h4>\n\n\n\n<p>Comprovada com resultado de uma prova oficial e v\u00e1lida at\u00e9 2 anos antes da aplica\u00e7\u00e3o. N\u00edvel m\u00ednimo CLB\/NCLC 7 para trabalhos TEER 0 ou 1 da NOC e CLB\/NCLC 5 para trabalhos TEER 2 e 3 da NOC.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Educa\u00e7\u00e3o<\/h4>\n\n\n\n<p>Apesar de educa\u00e7\u00e3o n\u00e3o ser um requisito para este programa, \u00e9 importante incluir se voc\u00ea tiver. Isso vai te garantir mais pontos para o rank geral do Express Entry, que vocu explicar a seguir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como funciona o Express Entry e como aplicar<\/h3>\n\n\n\n<p>O Express Entry funciona como um processo seletivo, em que os aplicantes recebem pontos baseados em v\u00e1rios fatores de qualifica\u00e7\u00e3o.<\/p>\n\n\n\n<p>De tempos em tempos, o governo do Canad\u00e1 faz uma rodada convidando candidatos com pontua\u00e7\u00f5es mais altas para aplicar. Ou seja, quanto mais completo e melhor for seu perfil, mais pontos voc\u00ea ter\u00e1 e maior sua chance de receber o convite para aplicar para um dos tr\u00eas programas.<\/p>\n\n\n\n<p>Portanto, o passo a passo para aplicar para um ou mais programas do Express Entry e tentar conseguir sua resid\u00eancia permanente no Canad\u00e1 \u00e9:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Descobrir se voc\u00ea \u00e9 eleg\u00edvel<\/strong> &#8211; Responda \u00e0 algumas perguntas <a href=\"https:\/\/onlineservices-servicesenligne.cic.gc.ca\/c2c\/eapp\" target=\"_blank\" rel=\"noreferrer noopener\">nesta p\u00e1gina para saber se voc\u00ea \u00e9 eleg\u00edvel em algum programa do Express Entry<\/a>;<\/li>\n\n\n\n<li><strong>Conferir sua pontua\u00e7\u00e3o<\/strong> &#8211; <a href=\"https:\/\/ircc.canada.ca\/english\/immigrate\/skilled\/crs-tool.asp\" target=\"_blank\" rel=\"noreferrer noopener\">Nesta p\u00e1gina voc\u00ea consegue calcular sua prov\u00e1vel pontua\u00e7\u00e3o<\/a> antes de criar um perfil no Express Entry;<\/li>\n\n\n\n<li><strong>Providenciar toda a documenta\u00e7\u00e3o<\/strong> &#8211; Algumas documenta\u00e7\u00f5es podem demorar, ent\u00e3o \u00e9 melhor providenciar tudo antes de receber um convite para aplica\u00e7\u00e3o, j\u00e1 que voc\u00ea ter\u00e1 um tempo limite para aplicar;<\/li>\n\n\n\n<li><strong>Crie um perfil no Express Entry<\/strong> &#8211; <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/application\/account.html\" target=\"_blank\" rel=\"noreferrer noopener\">Crie uma conta e preencha o formul\u00e1rio online<\/a>;<\/li>\n\n\n\n<li><strong>Aguarde um convite para aplicar<\/strong> &#8211; Se receber um convite, voc\u00ea ter\u00e1 60 dias para enviar sua aplica\u00e7\u00e3o;<\/li>\n\n\n\n<li><strong>Envie sua aplica\u00e7\u00e3o<\/strong> para imigrar para o Canad\u00e1 e se tornar um residente permanente.<\/li>\n<\/ol>\n\n\n\n<p>&gt;&gt; Se voc\u00ea quiser ter uma ideia de quantos pontos precisa para receber um convite para aplicar, <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/corporate\/mandate\/policies-operational-instructions-agreements\/ministerial-instructions\/express-entry-rounds.html\" target=\"_blank\" rel=\"noreferrer noopener\">confira aqui a nota de corte (pontua\u00e7\u00e3o m\u00ednima) das \u00faltimas rodadas<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2- Provincial Nominee Programs (PNPs): Nomia\u00e7\u00f5es Provinciais para imigrar para o Canad\u00e1<\/h2>\n\n\n\n<p>O Provincial Nominee Class (PNC) \u00e9 o programa de imigra\u00e7\u00e3o que permite com que voc\u00ea aplique para a <strong>resid\u00eancia permanente atrav\u00e9s da nomea\u00e7\u00e3o de uma prov\u00edncia canadense<\/strong>.<\/p>\n\n\n\n<p>Cada prov\u00edncia possui seu Provincial Nominee Program (PNP), com regras pr\u00f3prias, que escolhe imigrantes de acordo com as <strong>necessidades econ\u00f4micas da prov\u00edncia<\/strong>. Ap\u00f3s receber a nomea\u00e7\u00e3o provincial, voc\u00ea poder\u00e1 aplicar pelo site do governo federal do Canad\u00e1.<\/p>\n\n\n\n<p>Os PNP tamb\u00e9m costumam ter <strong>pelo menos um <\/strong><strong><em>stream<\/em><\/strong><strong> que se conecta ao Express Entry<\/strong>. Para receber uma nomea\u00e7\u00e3o em um desses <em>streams<\/em>, voc\u00ea precisa criar seu perfil no Express Entry e aguardar. A nomea\u00e7\u00e3o vale 600 pontos, o que geralmente garante seu convite em um dos tr\u00eas programas do EE.<\/p>\n\n\n\n<p>Apesar de cada prov\u00edncia exigir diferentes crit\u00e9rios e oferecer diferentes <em>streams<\/em> em seus PNPs, todas elas est\u00e3o interessadas em <strong>profissionais qualificados<\/strong>. Isso significa que as exig\u00eancia em comum em todas s\u00e3o bem parecidas com requisitos do EE, como experi\u00eancia de trabalho, educa\u00e7\u00e3o, profici\u00eancia em ingl\u00eas e\/ou franc\u00eas e a <em>job offer<\/em>.<\/p>\n\n\n\n<p>Veja a seguir as prov\u00edncias do Canad\u00e1 que oferecem programas de nomea\u00e7\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.alberta.ca\/ainp.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Alberta<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.welcomebc.ca\/PNP\" target=\"_blank\" rel=\"noreferrer noopener\">British Columbia<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.immigratemanitoba.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Manitoba<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.gnb.ca\/immigration\" target=\"_blank\" rel=\"noreferrer noopener\">New Brunswick<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.nlpnp.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Newfoundland and Labrador<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.immigratenwt.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Northwest Territories<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.novascotiaimmigration.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nova Scotia<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.ontarioimmigration.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ontario<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.immigratepei.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Prince Edward Island<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.saskatchewan.ca\/immigration\" target=\"_blank\" rel=\"noreferrer noopener\">Saskatchewan<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.immigration.gov.yk.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Yukon Territory<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">3- Atlantic Immigration Program: Imigre para as prov\u00edncias do atl\u00e2ntico<\/h2>\n\n\n\n<p>O <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/atlantic-immigration.html\" target=\"_blank\" rel=\"noreferrer noopener\">Atlantic Immigration Program<\/a> \u00e9 o programa de imigra\u00e7\u00e3o do Canad\u00e1 que ajuda trabalhadores qualificados (<em>skilled workers<\/em>) e estudantes internacionais (<em>international graduates<\/em>) a trabalharem e morarem em uma das 4 prov\u00edncias do Atl\u00e2ntico:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Newfoundland and Labrador<\/li>\n\n\n\n<li>Prince Edward Island<\/li>\n\n\n\n<li>Nova Scotia<\/li>\n\n\n\n<li>New Brunswick<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"288\" src=\"http:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Atlantic-immigration-program.png\" alt=\"Mapa do Canada, com as seguintes provincials destacadas: Newfoundland and Labrador, Prince Edward Island, Nova Scotia e New Brunswick.\" class=\"wp-image-3026\" srcset=\"https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Atlantic-immigration-program.png 400w, https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Atlantic-immigration-program-300x216.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p>O principal requisito deste programa \u00e9 a <em>job offer<\/em>, ou seja, <strong>oferta de trabalho de um empregador designado<\/strong> de uma das prov\u00edncias do Atl\u00e2ntico.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/atlantic-immigration\/how-to-immigrate\/job-offer.html\" target=\"_blank\" rel=\"noreferrer noopener\">&gt;&gt; Nesta p\u00e1gina, voc\u00ea encontra mais informa\u00e7\u00f5es sobre os requisitos da <em>job offer<\/em> e como encontrar um emprego com um empregador designado.<\/a><\/p>\n\n\n\n<p>Al\u00e9m da <em>job offer<\/em>, outros requisitos para ser eleg\u00edvel no Atlantic Immigration Program s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Para <\/strong><strong><em>Sikilled Workers<\/em><\/strong><strong>:<\/strong> Experi\u00eancia de trabalho qualificado de ao menos 1 ano na mesma NOC da sua <em>job offer<\/em>, em tempo integral, ou o equivalente em meio per\u00edodo;<\/li>\n\n\n\n<li><strong>Para <em>International Graduates<\/em>:<\/strong> Ensino superior completo, de ao menos 2 anos de dura\u00e7\u00e3o, em uma das <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/atlantic-immigration\/post-secondary-institutions.html\" target=\"_blank\" rel=\"noreferrer noopener\">institui\u00e7\u00f5es reconhecidas das prov\u00edncias do Atl\u00e2ntico<\/a>;<\/li>\n\n\n\n<li><strong>Profici\u00eancia em ingl\u00eas ou franc\u00eas<\/strong> de no m\u00ednimo CLB\/NCLC 5 para job offer no TEER 0, 1, 2 ou 3 da NOC ou CLB\/NCLC 4 para TEER 4;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/atlantic-immigration\/proof-funds.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Comprova\u00e7\u00e3o financeira<\/strong><\/a>, se voc\u00ea n\u00e3o j\u00e1 n\u00e3o estiver vivendo e morando no Canad\u00e1.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">4- Quebec: Programas de imigra\u00e7\u00e3o espec\u00edficos da prov\u00edncia franc\u00f3fona do Canad\u00e1<\/h2>\n\n\n\n<p>O Quebec, prov\u00edncia franc\u00f3fona do Canad\u00e1, possui seus pr\u00f3prios programas de imigra\u00e7\u00e3o. Eles s\u00e3o destinados \u00e0 trabalhadores qualificados com profici\u00eancia em franc\u00eas.<\/p>\n\n\n\n<p>Para se tornar residente permanente da prov\u00edncia do Quebec, voc\u00ea pode aplicar atrav\u00e9s dos seguintes programas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.quebec.ca\/en\/immigration\/work-quebec\/skilled-workers\/regular-skilled-worker-program\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Regular Skilled Worker Program (RSWP):<\/strong><\/a> para trabalhadores qualificados que j\u00e1 est\u00e3o na prov\u00edncia ou em outro lugar do mundo;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.quebec.ca\/en\/immigration\/work-quebec\/skilled-workers\/quebec-experience-program\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Qu\u00e9bec Experience Program (PEQ):<\/strong><\/a> para trabalhadores tempor\u00e1rios ou estudantes internacionais que se formaram em uma institui\u00e7\u00e3o do Quebec;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.quebec.ca\/en\/immigration\/work-quebec\/skilled-workers\/food-processing\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Permanent immigration pilot program for workers in food processing:<\/strong><\/a> para trabalhadores tempor\u00e1rios no setor de processamento de alimentos;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.quebec.ca\/en\/immigration\/work-quebec\/skilled-workers\/orderlies\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Permanent immigration pilot program for orderlies:<\/strong><\/a> para trabalhadores estrangeiros tempor\u00e1rios que trabalham como cuidadores;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.quebec.ca\/en\/immigration\/work-quebec\/skilled-workers\/artificial-intelligence\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Permanent immigration pilot program for workers in the artificial intelligence, information technologies and visual effects sectors:<\/strong><\/a> para trabalhadores nesses tr\u00eas setores em demanda no Quebec.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Como funciona a imigra\u00e7\u00e3o do Quebec e como aplicar<\/h3>\n\n\n\n<p>Pelo <strong>Regular Skilled Worker Program (RSWP)<\/strong>, o quebec avalia os candidatos com base em v\u00e1rios fatores como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>N\u00edvel educacional;<\/li>\n\n\n\n<li>Experi\u00eancia profissional;<\/li>\n\n\n\n<li>Idade: maior pontua\u00e7\u00e3o entre 18 e 35 anos;<\/li>\n\n\n\n<li>Profici\u00eancia nas l\u00ednguas oficiais, franc\u00eas \u00e9 um requisito m\u00ednimo;<\/li>\n\n\n\n<li>Estadia e fam\u00edlia no Quebec;<\/li>\n\n\n\n<li>Todos esses fatores tamb\u00e9m s\u00e3o avaliados para o c\u00f4njuge;<\/li>\n\n\n\n<li>Oferta de trabalho v\u00e1lida;<\/li>\n\n\n\n<li>Filhos: maior pontua\u00e7\u00e3o se menores de 12 anos;<\/li>\n\n\n\n<li>Capacidade financeira.<\/li>\n<\/ul>\n\n\n\n<p>Para aplicar, primeiro, voc\u00ea precisa <strong>expressar interesse pela plataforma online, <\/strong><a href=\"https:\/\/arrima.immigration-quebec.gouv.qc.ca\/aiguillage\/?\"><strong>Arrima<\/strong><\/a>, e aguardar um convite para a aplica\u00e7\u00e3o, que vai depender da sua pontua\u00e7\u00e3o. Recebendo o convite, voc\u00ea poder\u00e1 aplicar para a resid\u00eancia permanente com o Immigration, Refugees and Citizenship Canada (IRCC) do governo federal.<\/p>\n\n\n\n<p>Pelos outros programas, seu perfil precisa <strong>atender \u00e0s condi\u00e7\u00f5es gerais exigidas e aplicar por meio da Arrima<\/strong>. Pode ser que tamb\u00e9m seja necess\u00e1rio participar de uma entrevista com um agente de imigra\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Se sua aplica\u00e7\u00e3o for aprovada, voc\u00ea receber\u00e1 o<strong> Certificat de s\u00e9lection du Qu\u00e9bec<\/strong>, que \u00e9 um certificado exigido para a pr\u00f3xima etapa que \u00e9 a aplica\u00e7\u00e3o com o governo do Canad\u00e1.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5- Programas de imigra\u00e7\u00e3o para profiss\u00f5es espec\u00edficas<\/h2>\n\n\n\n<p>Tamb\u00e9m \u00e9 poss\u00edvel imigrar para o Canad\u00e1 por meio de programas de imigra\u00e7\u00e3o para profiss\u00f5es espec\u00edficas que est\u00e3o em alta demanda. Esses programas s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/caregivers.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Caregivers:<\/strong> para cuidadores<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/start-visa.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Start-up visa:<\/strong> para empreendedores<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/self-employed.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Self-employed:<\/strong> para profissionais aut\u00f4nomos de atividades culturais e atl\u00e9ticas<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/self-employed.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Agri-Food Pilot:<\/strong> para profissionais do setor agr\u00edcola<\/a><\/li>\n<\/ul>\n\n\n\n<p>Lembrando que a profici\u00eancia em ingl\u00eas ou franc\u00eas \u00e9 obrigat\u00f3ria em todos esses programas, assim como a forma\u00e7\u00e3o na \u00e1rea. Em alguns, a experi\u00eancia qualificada tamb\u00e9m \u00e9 requisitada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6- Family Sponsorship: Com o patroc\u00ednio de um residente permanente ou cidad\u00e3o canadense<\/h2>\n\n\n\n<p>Se voc\u00ea possui um <strong>membro da fam\u00edlia<\/strong> que \u00e9 um residente permanente ou cidad\u00e3o canadense, essa pessoa pode te ajudar a imigrar para o Canad\u00e1 e conseguir seu PR atrav\u00e9s do programa <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/family-sponsorship.html\" target=\"_blank\" rel=\"noreferrer noopener\">Family Sponsorship<\/a>.<\/p>\n\n\n\n<p>Esse programa exige que <strong>o residente permanente ou cidad\u00e3o canadense seja maior de 18 e se comprometa a patrocinar o imigrante<\/strong>, declarando ser respons\u00e1vel por suas necessidades financeiras pelo tempo exigido pelo governo.<\/p>\n\n\n\n<p>O <em>sponsor<\/em>, ou seja, o patrocinador, n\u00e3o precisa necessariamente ser seu respons\u00e1vel financeiro, mas legalmente, essa pessoa precisa assinar uma declara\u00e7\u00e3o para a aplica\u00e7\u00e3o. Tamb\u00e9m \u00e9 necess\u00e1rio comprovar o v\u00ednculo relacional com documentos e refer\u00eancias.<\/p>\n\n\n\n<p>Os membros da fam\u00edlia que podem ser patrocinados, s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>C\u00f4njuge, parceiro em uni\u00e3o est\u00e1vel ou filhos dependentes;<\/li>\n\n\n\n<li>Filhos adotivos;<\/li>\n\n\n\n<li>Pais e av\u00f3s;<\/li>\n\n\n\n<li>Irm\u00e3os, sobrinhos ou netos \u00f3rf\u00e3os.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">N\u00e3o faltam oportunidades para imigrar para o Canad\u00e1<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1000\" height=\"500\" src=\"http:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/imigrar-para-o-canada-conclusao.png\" alt=\"Nayara segurando as bandeirinhas do Canad\u00e1 nas ruas de Toronto.\" class=\"wp-image-3024\" srcset=\"https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/imigrar-para-o-canada-conclusao.png 1000w, https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/imigrar-para-o-canada-conclusao-300x150.png 300w, https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/imigrar-para-o-canada-conclusao-768x384.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>S\u00f3 depende de voc\u00ea! Se esse \u00e9 seu objetivo, crie um plano a longo-prazo, estude muito sobre o assunto e prepare-se!<\/p>\n\n\n\n<p>Meu plano para imigrar para o Canad\u00e1 come\u00e7ou l\u00e1 em 2019 e, s\u00f3 agora, em 2024, fui convidada para aplicar tanto pela prov\u00edncia de Ontario, em um dos PNPs, como tamb\u00e9m pelo Canadian Experience Class do EE.<\/p>\n\n\n\n<p>Como eu falei, acredito que por meio dos estudos seja um dos caminhos mais efetivos e garantidos.<\/p>\n\n\n\n<p><a href=\"https:\/\/nayandtheplanet.com\/pt-br\/faculdade-no-canada\/\" target=\"_blank\" rel=\"noreferrer noopener\">&gt;&gt; Confira este guia completo sobre como fazer faculdade no Canad\u00e1!<\/a><\/p>\n\n\n\n<p><strong>Os estudos te d\u00e3o uma chance maior de receber um convite para o Express Entry<\/strong>, que \u00e9 um dos programas de imigra\u00e7\u00e3o mais r\u00e1pidos do Canad\u00e1. Esse foi o meu caso, e escolhi aplicar por esse programa.<\/p>\n\n\n\n<p>O que acontece \u00e9 que, ap\u00f3s completar seus estudos, voc\u00ea pode aplicar para a permiss\u00e3o de trabalho chamada <strong>Post Graduate Work Permit (PGWP)<\/strong>. Programas de 1 ano, te d\u00e3o direito a trabalhar no Canad\u00e1 por 1 ano ap\u00f3s a conclus\u00e3o do curso. Programas de 2, assim como foi o meu, te d\u00e3o direito a 3 anos de permiss\u00e3o de trabalho e assim por diante.<\/p>\n\n\n\n<p>Nesse tempo, voc\u00ea pode come\u00e7ar a trabalhar em uma das profiss\u00f5es da NOC, ganhar experi\u00eancia qualificada e, consequentemente, ganhar pontos para aplicar para a imigra\u00e7\u00e3o. Vale a pena o esfor\u00e7o e o dinheiro!<\/p>\n\n\n\n<p>Claro que, se voc\u00ea j\u00e1 tem experi\u00eancia em uma das profiss\u00f5es em demanda no Canad\u00e1 e tem um n\u00edvel alto de profici\u00eancia em ingl\u00eas ou franc\u00eas, talvez os outros programas sejam vantajosos para voc\u00ea aplicar estando do Brasil mesmo.<\/p>\n\n\n\n<p>Mas lembre-se que <strong>todos os programas consideram a <\/strong><strong><em>job offer <\/em><\/strong><strong>imprescind\u00edvel<\/strong>. Com tantos imigrantes que j\u00e1 est\u00e3o no Canad\u00e1, com forma\u00e7\u00e3o daqui, procurando por trabalho, \u00e9 bem raro uma empresa querer contratar um profissional que esteja em outro pa\u00eds.<\/p>\n\n\n\n<p><strong>Voc\u00ea j\u00e1 \u00e9 eleg\u00edvel para algum programa de imigra\u00e7\u00e3o?<\/strong> \u00c9 hora de pegar o seu PR!<\/p>\n\n\n\n<p>Todas as informa\u00e7\u00f5es que passei aqui est\u00e3o bem completas no <a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada.html\" target=\"_blank\" rel=\"noreferrer noopener\">site oficial do governo do Canad\u00e1<\/a>! Escolha seu programa, confira os requisitos, os documentos necess\u00e1rios e comece a preencher os formul\u00e1rios.<\/p>\n\n\n\n<p>Todos os programas cobram um<strong> <\/strong><strong><em>fee<\/em><\/strong><strong> de aplica\u00e7\u00e3o<\/strong> e o tempo de processamento varia muito, podendo ser entre 5 meses at\u00e9 4 anos em alguns programas.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.canada.ca\/en\/immigration-refugees-citizenship\/services\/immigrate-canada\/how-to-apply-online.html\" target=\"_blank\" rel=\"noreferrer noopener\">&gt;&gt; As instru\u00e7\u00f5es para cada programa e o portal de aplica\u00e7\u00e3o podem ser acessados por este link!<\/a><\/p>\n\n\n\n<p>Se tiver alguma d\u00favida, deixa nos coment\u00e1rios, que irei responder!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea tem planos de imigrar para o Canad\u00e1? Confira um guia completo com os requisitos de todos os programas dispon\u00edveis e torne-se um residente permanente!<\/p>\n","protected":false},"author":2,"featured_media":3205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canada-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imigrar para o Canad\u00e1: o guia completo de como obter o PR [2024]<\/title>\n<meta name=\"description\" content=\"Voc\u00ea tem planos de imigrar para o Canad\u00e1? Confira um guia completo com os requisitos de todos os programas e torne-se residente permanente!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imigrar para o Canad\u00e1: o guia completo de como obter o PR [2024]\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea tem planos de imigrar para o Canad\u00e1? Confira um guia completo com os requisitos de todos os programas e torne-se residente permanente!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"Nay and the Planet\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-19T19:18:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-18T23:03:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nayara Byrne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nayara Byrne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/\"},\"author\":{\"name\":\"Nayara Byrne\",\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/c7b7228d0d95afd2174664e128b159e6\"},\"headline\":\"Como imigrar para o Canad\u00e1\",\"datePublished\":\"2024-03-19T19:18:26+00:00\",\"dateModified\":\"2025-03-18T23:03:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/\"},\"wordCount\":3176,\"publisher\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nayandtheplanet.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Imigrar-pro-Canada.png\",\"articleSection\":[\"Canada\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/\",\"url\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/\",\"name\":\"Imigrar para o Canad\u00e1: o guia completo de como obter o PR [2024]\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nayandtheplanet.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Imigrar-pro-Canada.png\",\"datePublished\":\"2024-03-19T19:18:26+00:00\",\"dateModified\":\"2025-03-18T23:03:33+00:00\",\"description\":\"Voc\u00ea tem planos de imigrar para o Canad\u00e1? Confira um guia completo com os requisitos de todos os programas e torne-se residente permanente!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nayandtheplanet.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Imigrar-pro-Canada.png\",\"contentUrl\":\"https:\\\/\\\/nayandtheplanet.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Imigrar-pro-Canada.png\",\"width\":960,\"height\":540,\"caption\":\"Imigrar para o Canad\u00e1: Nayara segura a bandeira do Canad\u00e1 em Banff\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/imigrar-para-o-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como imigrar para o Canad\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/\",\"name\":\"Nay and the Planet\",\"description\":\"Travel &amp; Lifestyle Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/#organization\",\"name\":\"Nay and the Planet\",\"url\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nayandtheplanet.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Nay-and-the-planet-site-icon-2.png\",\"contentUrl\":\"https:\\\/\\\/nayandtheplanet.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Nay-and-the-planet-site-icon-2.png\",\"width\":512,\"height\":512,\"caption\":\"Nay and the Planet\"},\"image\":{\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/c7b7228d0d95afd2174664e128b159e6\",\"name\":\"Nayara Byrne\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c1c24a7433a2229b4dbcef4d38222aa47503b5ce5d67c3e22fc10d0a56a9308?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c1c24a7433a2229b4dbcef4d38222aa47503b5ce5d67c3e22fc10d0a56a9308?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c1c24a7433a2229b4dbcef4d38222aa47503b5ce5d67c3e22fc10d0a56a9308?s=96&d=mm&r=g\",\"caption\":\"Nayara Byrne\"},\"url\":\"https:\\\/\\\/nayandtheplanet.com\\\/pt-br\\\/author\\\/nayara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imigrar para o Canad\u00e1: o guia completo de como obter o PR [2024]","description":"Voc\u00ea tem planos de imigrar para o Canad\u00e1? Confira um guia completo com os requisitos de todos os programas e torne-se residente permanente!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/","og_locale":"pt_BR","og_type":"article","og_title":"Imigrar para o Canad\u00e1: o guia completo de como obter o PR [2024]","og_description":"Voc\u00ea tem planos de imigrar para o Canad\u00e1? Confira um guia completo com os requisitos de todos os programas e torne-se residente permanente!","og_url":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/","og_site_name":"Nay and the Planet","article_published_time":"2024-03-19T19:18:26+00:00","article_modified_time":"2025-03-18T23:03:33+00:00","og_image":[{"width":960,"height":540,"url":"http:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png","type":"image\/png"}],"author":"Nayara Byrne","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nayara Byrne","Est. tempo de leitura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/#article","isPartOf":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/"},"author":{"name":"Nayara Byrne","@id":"https:\/\/nayandtheplanet.com\/pt-br\/#\/schema\/person\/c7b7228d0d95afd2174664e128b159e6"},"headline":"Como imigrar para o Canad\u00e1","datePublished":"2024-03-19T19:18:26+00:00","dateModified":"2025-03-18T23:03:33+00:00","mainEntityOfPage":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/"},"wordCount":3176,"publisher":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png","articleSection":["Canada"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/","url":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/","name":"Imigrar para o Canad\u00e1: o guia completo de como obter o PR [2024]","isPartOf":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/#primaryimage"},"image":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png","datePublished":"2024-03-19T19:18:26+00:00","dateModified":"2025-03-18T23:03:33+00:00","description":"Voc\u00ea tem planos de imigrar para o Canad\u00e1? Confira um guia completo com os requisitos de todos os programas e torne-se residente permanente!","breadcrumb":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/#primaryimage","url":"https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png","contentUrl":"https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png","width":960,"height":540,"caption":"Imigrar para o Canad\u00e1: Nayara segura a bandeira do Canad\u00e1 em Banff"},{"@type":"BreadcrumbList","@id":"https:\/\/nayandtheplanet.com\/pt-br\/imigrar-para-o-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nayandtheplanet.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Como imigrar para o Canad\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/nayandtheplanet.com\/pt-br\/#website","url":"https:\/\/nayandtheplanet.com\/pt-br\/","name":"Nay and the Planet","description":"Travel &amp; Lifestyle Blog","publisher":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nayandtheplanet.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nayandtheplanet.com\/pt-br\/#organization","name":"Nay and the Planet","url":"https:\/\/nayandtheplanet.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nayandtheplanet.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2021\/01\/cropped-Nay-and-the-planet-site-icon-2.png","contentUrl":"https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2021\/01\/cropped-Nay-and-the-planet-site-icon-2.png","width":512,"height":512,"caption":"Nay and the Planet"},"image":{"@id":"https:\/\/nayandtheplanet.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nayandtheplanet.com\/pt-br\/#\/schema\/person\/c7b7228d0d95afd2174664e128b159e6","name":"Nayara Byrne","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c1c24a7433a2229b4dbcef4d38222aa47503b5ce5d67c3e22fc10d0a56a9308?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c1c24a7433a2229b4dbcef4d38222aa47503b5ce5d67c3e22fc10d0a56a9308?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c1c24a7433a2229b4dbcef4d38222aa47503b5ce5d67c3e22fc10d0a56a9308?s=96&d=mm&r=g","caption":"Nayara Byrne"},"url":"https:\/\/nayandtheplanet.com\/pt-br\/author\/nayara\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png",960,540,false],"thumbnail":["https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada-150x150.png",150,150,true],"medium":["https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada-300x169.png",300,169,true],"medium_large":["https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada-768x432.png",768,432,true],"large":["https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png",960,540,false],"1536x1536":["https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png",960,540,false],"2048x2048":["https:\/\/nayandtheplanet.com\/wp-content\/uploads\/2024\/03\/Imigrar-pro-Canada.png",960,540,false]},"uagb_author_info":{"display_name":"Nayara Byrne","author_link":"https:\/\/nayandtheplanet.com\/pt-br\/author\/nayara\/"},"uagb_comment_info":0,"uagb_excerpt":"Voc\u00ea tem planos de imigrar para o Canad\u00e1? Confira um guia completo com os requisitos de todos os programas dispon\u00edveis e torne-se um residente permanente!","_links":{"self":[{"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/posts\/3029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/comments?post=3029"}],"version-history":[{"count":6,"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/posts\/3029\/revisions"}],"predecessor-version":[{"id":3208,"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/posts\/3029\/revisions\/3208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/media\/3205"}],"wp:attachment":[{"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/media?parent=3029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/categories?post=3029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nayandtheplanet.com\/pt-br\/wp-json\/wp\/v2\/tags?post=3029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}